{"id":246,"count":35,"description":"","link":"https:\/\/uniquevenuesofamsterdam.com\/en\/guests\/50-100\/","name":"50-100","slug":"50-100","taxonomy":"guests","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>50-100 Archieven - Unique Venues of Amsterdam<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uniquevenuesofamsterdam.com\/en\/wp-json\/wp\/v2\/guests\/246\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"50-100 Archieven - Unique Venues of Amsterdam\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniquevenuesofamsterdam.com\/en\/guests\/50-100\/\" \/>\n<meta property=\"og:site_name\" content=\"Unique Venues of Amsterdam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/en\\\/guests\\\/50-100\\\/\",\"url\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/en\\\/guests\\\/50-100\\\/\",\"name\":\"50-100 Archieven - Unique Venues of Amsterdam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/en\\\/guests\\\/50-100\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/en\\\/guests\\\/50-100\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"50-100\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/#website\",\"url\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/\",\"name\":\"Unique Venues of Amsterdam\",\"description\":\"Uitzonderlijke evenementenlocaties\",\"publisher\":{\"@id\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/#organization\",\"name\":\"Unique Venues of Amsterdam\",\"url\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/UV_logo_pin.svg\",\"contentUrl\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/UV_logo_pin.svg\",\"caption\":\"Unique Venues of Amsterdam\"},\"image\":{\"@id\":\"https:\\\/\\\/uniquevenuesofamsterdam.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"50-100 Archieven - Unique Venues of Amsterdam","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uniquevenuesofamsterdam.com\/en\/wp-json\/wp\/v2\/guests\/246","og_locale":"en_GB","og_type":"article","og_title":"50-100 Archieven - Unique Venues of Amsterdam","og_url":"https:\/\/uniquevenuesofamsterdam.com\/en\/guests\/50-100\/","og_site_name":"Unique Venues of Amsterdam","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/uniquevenuesofamsterdam.com\/en\/guests\/50-100\/","url":"https:\/\/uniquevenuesofamsterdam.com\/en\/guests\/50-100\/","name":"50-100 Archieven - Unique Venues of Amsterdam","isPartOf":{"@id":"https:\/\/uniquevenuesofamsterdam.com\/#website"},"breadcrumb":{"@id":"https:\/\/uniquevenuesofamsterdam.com\/en\/guests\/50-100\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/uniquevenuesofamsterdam.com\/en\/guests\/50-100\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uniquevenuesofamsterdam.com\/"},{"@type":"ListItem","position":2,"name":"50-100"}]},{"@type":"WebSite","@id":"https:\/\/uniquevenuesofamsterdam.com\/#website","url":"https:\/\/uniquevenuesofamsterdam.com\/","name":"Unique Venues of Amsterdam","description":"Uitzonderlijke evenementenlocaties","publisher":{"@id":"https:\/\/uniquevenuesofamsterdam.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniquevenuesofamsterdam.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/uniquevenuesofamsterdam.com\/#organization","name":"Unique Venues of Amsterdam","url":"https:\/\/uniquevenuesofamsterdam.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/uniquevenuesofamsterdam.com\/#\/schema\/logo\/image\/","url":"https:\/\/uniquevenuesofamsterdam.com\/wp-content\/uploads\/2021\/03\/UV_logo_pin.svg","contentUrl":"https:\/\/uniquevenuesofamsterdam.com\/wp-content\/uploads\/2021\/03\/UV_logo_pin.svg","caption":"Unique Venues of Amsterdam"},"image":{"@id":"https:\/\/uniquevenuesofamsterdam.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/uniquevenuesofamsterdam.com\/en\/wp-json\/wp\/v2\/guests\/246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniquevenuesofamsterdam.com\/en\/wp-json\/wp\/v2\/guests"}],"about":[{"href":"https:\/\/uniquevenuesofamsterdam.com\/en\/wp-json\/wp\/v2\/taxonomies\/guests"}],"wp:post_type":[{"href":"https:\/\/uniquevenuesofamsterdam.com\/en\/wp-json\/wp\/v2\/venue?guests=246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}